{"id":50314,"date":"2022-01-28T17:06:10","date_gmt":"2022-01-28T16:06:10","guid":{"rendered":"https:\/\/socialgoodaccelerator.eu\/?p=50314"},"modified":"2025-10-20T12:31:42","modified_gmt":"2025-10-20T10:31:42","slug":"social-good-week-retour-sur-la-premiere-table-ronde-europeenne","status":"publish","type":"post","link":"https:\/\/socialgoodaccelerator.eu\/fr\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/","title":{"rendered":"Social Good Week : retour sur la premi\u00e8re table ronde europ\u00e9enne"},"content":{"rendered":"[et_pb_section fb_built=&#8221;1&#8243; theme_builder_area=&#8221;post_content&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; theme_builder_area=&#8221;post_content&#8221;]<h1 style=\"text-align: justify;\">Social Good Week : retour sur la premi\u00e8re table ronde europ\u00e9enne<\/h1>[\/et_pb_text][et_pb_text admin_label=&#8221;Texte&#8221; _builder_version=&#8221;4.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;|15px||15px|false|false&#8221; hover_enabled=&#8221;0&#8243; use_border_color=&#8221;off&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221; text_text_color=&#8221;#FFFFFF&#8221; sticky_enabled=&#8221;0&#8243; theme_builder_area=&#8221;post_content&#8221; background_color=&#8221;#2B2A5C&#8221;]<p>Le <strong data-start=\"487\" data-end=\"501\">25 janvier<\/strong>, le <strong data-start=\"506\" data-end=\"540\">Social Good Accelerator (SOGA)<\/strong>, en partenariat avec <strong data-start=\"562\" data-end=\"587\">Social Economy Europe<\/strong>, a coorganis\u00e9 le <strong data-start=\"605\" data-end=\"658\">premier \u00e9v\u00e9nement europ\u00e9en de la Social Good Week<\/strong>.<br data-start=\"659\" data-end=\"662\" \/>Quatre ans apr\u00e8s sa derni\u00e8re \u00e9dition initi\u00e9e par <strong data-start=\"711\" data-end=\"724\">HelloAsso<\/strong>, le SOGA a <strong data-start=\"736\" data-end=\"758\">repris le flambeau<\/strong> pour une <strong data-start=\"768\" data-end=\"811\">nouvelle \u00e9dition \u00e0 dimension europ\u00e9enne<\/strong>.<\/p>\n<p>Cette <strong data-start=\"820\" data-end=\"844\">premi\u00e8re table ronde<\/strong>, consacr\u00e9e au <strong data-start=\"859\" data-end=\"924\">changement d\u2019\u00e9chelle de l\u2019\u00e9conomie sociale et solidaire (ESS)<\/strong>, a \u00e9t\u00e9 <strong data-start=\"932\" data-end=\"971\">diffus\u00e9e en direct depuis Bruxelles<\/strong> aupr\u00e8s d\u2019une centaine de participants connect\u00e9s.<br data-start=\"1020\" data-end=\"1023\" \/>L\u2019occasion de rappeler le <strong data-start=\"1049\" data-end=\"1081\">contexte politique favorable<\/strong> \u00e0 une approche europ\u00e9enne du num\u00e9rique d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral : entre le <strong data-start=\"1150\" data-end=\"1171\">Data Services Act<\/strong>, la <strong data-start=\"1176\" data-end=\"1210\">D\u00e9cennie num\u00e9rique de l\u2019Europe<\/strong>, le <strong data-start=\"1215\" data-end=\"1245\">Pacte pour les comp\u00e9tences<\/strong> et le <strong data-start=\"1252\" data-end=\"1293\">Plan d\u2019action pour l\u2019\u00e9conomie sociale<\/strong>, les politiques publiques europ\u00e9ennes convergent de plus en plus vers les valeurs du secteur.<\/p>[\/et_pb_text][et_pb_image src=&#8221;http:\/\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/01\/event-cover-5937.png&#8221; alt=&#8221;Finals Social Economy Awards&#8221; title_text=&#8221;event-cover&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;84%&#8221; custom_margin=&#8221;34px||5px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;84%&#8221; module_alignment=&#8221;center&#8221; min_height=&#8221;56px&#8221; custom_padding=&#8221;0px||0px|||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<h6 style=\"text-align: center;\"><span style=\"color: #163074; font-size: small;\">Affiche du premier pr\u00e9-lancement de la Social Good Week, co-organis\u00e9e par le Social Good Accelerator (SOGA) et Social Economy Europe<br \/><\/span><\/h6>\n<h6 style=\"text-align: center;\"><em><span style=\"color: #163074; font-size: x-small;\">Source: Social Good Accelerator<br \/><\/span><\/em><\/h6>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; theme_builder_area=&#8221;post_content&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; column_structure=&#8221;2_5,3_5&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;2_5&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;http:\/\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/01\/B9725064525Z.1_20201027105409_000G70GV0171.1-0.jpg&#8221; alt=&#8221;Conference FNAF 2021&#8243; title_text=&#8221;unnamed (2)&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-1px||0px|||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px|||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<h6><span style=\"color: #163074; font-size: small;\">Barbara Trachte intevenes at the Brussels regional Parliament<\/span><\/h6>\n<h6><span style=\"font-size: x-small;\"><em><span style=\"color: #163074;\">Source: Belga<br \/><\/span><\/em><\/span><\/h6>[\/et_pb_text][\/et_pb_column][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;3_5&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;279px&#8221; custom_margin=&#8221;-26px||-1px|||&#8221; custom_padding=&#8221;||0px|||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; theme_builder_area=&#8221;post_content&#8221;]<h2> Les constats et ambitions des d\u00e9cideurs europ\u00e9ens <\/h2>\n\nLa premi\u00e8re intervenante, <strong data-start=\"1478\" data-end=\"1497\">Barbara Trachte<\/strong>, secr\u00e9taire d\u2019\u00c9tat \u00e0 la Transition \u00e9conomique et \u00e0 la Recherche scientifique de la R\u00e9gion de Bruxelles-Capitale, a ouvert la table ronde en r\u00e9affirmant <strong data-start=\"1650\" data-end=\"1722\">son engagement pour l\u2019innovation, l\u2019\u00e9conomie sociale et le num\u00e9rique<\/strong>.<br data-start=\"1723\" data-end=\"1726\" \/>Elle a pr\u00e9sent\u00e9 le <strong data-start=\"1745\" data-end=\"1785\">Plan r\u00e9gional d\u2019innovation 2022-2027<\/strong>, qui soutient les initiatives r\u00e9pondant \u00e0 des <strong data-start=\"1832\" data-end=\"1881\">besoins soci\u00e9taux \u00e9mergents ou non satisfaits<\/strong>, et salu\u00e9 l\u2019action du SOGA pour avoir <strong data-start=\"1920\" data-end=\"1995\">port\u00e9 la transition num\u00e9rique de l\u2019\u00e9conomie sociale \u00e0 l\u2019agenda europ\u00e9en<\/strong>.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; column_structure=&#8221;3_5,2_5&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;3_5&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|||||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; theme_builder_area=&#8221;post_content&#8221;]<p data-start=\"1998\" data-end=\"2574\">Les mod\u00e9rateurs <strong data-start=\"2014\" data-end=\"2034\">Jeanne Bret\u00e9cher<\/strong> (pr\u00e9sidente du SOGA) et <strong data-start=\"2059\" data-end=\"2078\">V\u00edctor Meseguer<\/strong> (directeur de Social Economy Europe) ont ensuite invit\u00e9 <strong data-start=\"2135\" data-end=\"2152\">Rowan Barnett<\/strong>, directeur de la <strong data-start=\"2170\" data-end=\"2235\">Google Foundation pour l\u2019Europe, le Moyen-Orient et l\u2019Afrique<\/strong>, \u00e0 pr\u00e9senter la vision du g\u00e9ant am\u00e9ricain.<br data-start=\"2278\" data-end=\"2281\" \/>Interrog\u00e9 sur les r\u00e9ticences des acteurs de l\u2019\u00e9conomie sociale vis-\u00e0-vis des outils GAFAM, Barnett a d\u00e9fendu une approche ouverte, affirmant que Google souhaite <strong data-start=\"2442\" data-end=\"2475\">soutenir l\u2019innovation sociale<\/strong> via un <strong data-start=\"2483\" data-end=\"2524\">fonds europ\u00e9en de 20 millions d\u2019euros<\/strong> destin\u00e9 \u00e0 renforcer la digitalisation du secteur.<\/p>\n<p data-start=\"2576\" data-end=\"3065\">Puis <strong data-start=\"2581\" data-end=\"2596\">Isidro Laso<\/strong>, conseiller aupr\u00e8s de la commissaire europ\u00e9enne \u00e0 l\u2019innovation et \u00e0 la jeunesse <strong data-start=\"2677\" data-end=\"2695\">Mariya Gabriel<\/strong>, a rappel\u00e9 le r\u00f4le de la Commission europ\u00e9enne dans <strong data-start=\"2748\" data-end=\"2798\">l\u2019\u00e9mergence de nouvelles formes de coop\u00e9ration<\/strong> entre recherche, innovation et \u00e9conomie sociale.<br data-start=\"2847\" data-end=\"2850\" \/>Il a soulign\u00e9 les nombreux <strong data-start=\"2877\" data-end=\"2970\">ponts entre l\u2019agenda europ\u00e9en de la recherche et le plan d\u2019action pour l\u2019\u00e9conomie sociale<\/strong>, confirmant la volont\u00e9 de Bruxelles d\u2019en faire un <strong data-start=\"3021\" data-end=\"3064\">levier majeur de transformation durable<\/strong>.<\/p>[\/et_pb_text][\/et_pb_column][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;2_5&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;http:\/\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-28-a\u0300-17.24.34.png&#8221; alt=&#8221;ActSE 2021 SOGA&#8221; title_text=&#8221;unnamed copie&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px|||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; theme_builder_area=&#8221;post_content&#8221;]<h6><span style=\"color: #163074; font-size: small;\">Rowan Barnett pr\u00e9sente l&#8217;approche de la Fondation Google pour soutenir l&#8217;Economie Sociale et Solidaire \u00e0 la Social Good Week.<\/span><span style=\"color: #163074; font-size: small;\"><\/span><\/h6>\n<h6><em><span style=\"color: #163074; font-size: x-small;\">Source: Social Good Accelerator<br \/><\/span><\/em><\/h6>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; column_structure=&#8221;2_5,3_5&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;2_5&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;http:\/\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/01\/artworks-Y54dsSNSzPWrH3Qs-PioMlQ-t500x500.jpeg&#8221; alt=&#8221;Gabriela Martin ActSE&#8221; title_text=&#8221;unnamed (1)&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px|||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<h6><span style=\"color: #163074; font-size: small;\">Julie Foulon souligne la n\u00e9cessit\u00e9 de faire de l&#8217;\u00e9galit\u00e9 des genres dans le secteur num\u00e9rique un objectif \u00e0 atteindre dans les prochaines ann\u00e9es.<br \/><\/span><\/h6>\n<h6><em><span style=\"color: #163074; font-size: x-small;\">Source: Girleek<br \/><\/span><\/em><\/h6>[\/et_pb_text][\/et_pb_column][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;3_5&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|||||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; theme_builder_area=&#8221;post_content&#8221;]<h2>Des acteurs bruxellois engag\u00e9s pour un num\u00e9rique inclusif<\/h2>\n<p>La seconde partie de la rencontre a mis en lumi\u00e8re plusieurs <strong data-start=\"3198\" data-end=\"3253\">acteurs embl\u00e9matiques de la Social Tech \u00e0 Bruxelles<\/strong>.<\/p>\n<p data-start=\"3256\" data-end=\"3632\"><strong data-start=\"3256\" data-end=\"3272\">Julie Foulon<\/strong>, fondatrice de <strong data-start=\"3288\" data-end=\"3299\">Girleek<\/strong> et cofondatrice de <strong data-start=\"3319\" data-end=\"3332\">Molengeek<\/strong>, a d\u00e9fendu la <strong data-start=\"3347\" data-end=\"3383\">parit\u00e9 dans le secteur num\u00e9rique<\/strong> et pr\u00e9sent\u00e9 ses programmes de <strong data-start=\"3414\" data-end=\"3461\">formation des femmes aux m\u00e9tiers de la tech<\/strong>.<br data-start=\"3462\" data-end=\"3465\" \/>Elle a rappel\u00e9 que l\u2019\u00e9conomie sociale constitue un <strong data-start=\"3516\" data-end=\"3540\">terreau d\u2019innovation<\/strong> indispensable pour rendre la transformation num\u00e9rique <strong data-start=\"3595\" data-end=\"3631\">plus \u00e9quitable et plus inclusive<\/strong>.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; column_structure=&#8221;3_5,2_5&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;3_5&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-48px|||||&#8221; custom_padding=&#8221;0px|||||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; theme_builder_area=&#8221;post_content&#8221;]<p data-start=\"3989\" data-end=\"4538\"><strong data-start=\"3634\" data-end=\"3651\">Chanel Genova<\/strong>, strat\u00e9giste num\u00e9rique au sein de <strong data-start=\"3686\" data-end=\"3700\">SocialWare<\/strong>, a ensuite expos\u00e9 la strat\u00e9gie de son association en lien avec le plan d\u2019action europ\u00e9en pour l\u2019\u00e9conomie sociale.<br data-start=\"3814\" data-end=\"3817\" \/>Elle a insist\u00e9 sur la <strong data-start=\"3839\" data-end=\"3878\">n\u00e9cessit\u00e9 du soutien institutionnel<\/strong> et sur l\u2019importance de <strong data-start=\"3902\" data-end=\"3941\">faire passer \u00e0 l\u2019\u00e9chelle europ\u00e9enne<\/strong> les solutions d\u00e9j\u00e0 mises en \u0153uvre localement.<\/p>\n<p>Enfin, <strong data-start=\"3996\" data-end=\"4010\">Carl M\u00f6rch<\/strong>, directeur de <strong data-start=\"4025\" data-end=\"4033\">FARI<\/strong>, l\u2019Institut bruxellois de l\u2019intelligence artificielle pour le bien commun (cr\u00e9\u00e9 par l\u2019Universit\u00e9 libre de Bruxelles, la VUB et le gouvernement r\u00e9gional), a pr\u00e9sent\u00e9 les <strong data-start=\"4203\" data-end=\"4270\">enjeux de la recherche sur l\u2019IA \u00e9thique et les donn\u00e9es ouvertes<\/strong>.<br data-start=\"4271\" data-end=\"4274\" \/>Ainsi, il a cit\u00e9 plusieurs acteurs-cl\u00e9s du financement de la recherche \u00e0 impact social, tels que la <strong data-start=\"4367\" data-end=\"4402\">Fondation Bettencourt Schueller<\/strong> ou la <strong data-start=\"4409\" data-end=\"4435\">Fondation Roi Baudouin<\/strong>, qui soutiennent les initiatives en faveur d\u2019un <strong data-start=\"4484\" data-end=\"4537\">num\u00e9rique responsable et d\u2019une innovation ouverte<\/strong>.<span style=\"color: #163074;\"><\/span><\/p>[\/et_pb_text][\/et_pb_column][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;2_5&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;http:\/\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-28-a\u0300-17.30.02.png&#8221; alt=&#8221;ActSE 2021 SOGA&#8221; title_text=&#8221;p052690-848898-scaled&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-44px||0px|||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px|||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<h6><span style=\"color: #163074; font-size: small;\">Carl M\u00f6rch pr\u00e9sente les travaux men\u00e9s par FARI, l&#8217;Institut de l&#8217;Intelligence Artificielle pour le bien commun bas\u00e9 \u00e0 Bruxelles, Belgique<br \/><\/span><\/h6>\n<h6><em><span style=\"color: #163074; font-size: x-small;\">Source: Social Good Week<br \/><\/span><\/em><\/h6>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_heading title=&#8221;Une dynamique europ\u00e9enne en marche&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; title_level=&#8221;h2&#8243; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p data-start=\"4587\" data-end=\"4756\">La diversit\u00e9 du panel a permis de d\u00e9gager <strong data-start=\"4629\" data-end=\"4660\">des pr\u00e9occupations communes<\/strong> :<br data-start=\"4662\" data-end=\"4665\" \/>comment concilier innovation technologique, gouvernance d\u00e9mocratique et int\u00e9r\u00eat g\u00e9n\u00e9ral ?<\/p>\n<p data-start=\"4758\" data-end=\"4962\">Les \u00e9changes ont mis en lumi\u00e8re <strong data-start=\"4790\" data-end=\"4860\">l\u2019\u00e9mergence d\u2019un v\u00e9ritable \u00e9cosyst\u00e8me europ\u00e9en du num\u00e9rique social<\/strong>, soutenu par des politiques publiques ambitieuses et port\u00e9 par des initiatives locales inspirantes.<\/p>\n<p data-start=\"4964\" data-end=\"5420\">Les ambitions sont fortes, les synergies nombreuses et les politiques de plus en plus align\u00e9es.<br data-start=\"5059\" data-end=\"5062\" \/>Une question demeure : <strong data-start=\"5085\" data-end=\"5173\">comment ces ambitions seront-elles concr\u00e8tement mises en \u0153uvre sur les territoires ?<\/strong><br data-start=\"5173\" data-end=\"5176\" \/>Seul le temps le dira.<br data-start=\"5198\" data-end=\"5201\" \/>En attendant, le <strong data-start=\"5218\" data-end=\"5245\">Social Good Accelerator<\/strong>, ses partenaires et la communaut\u00e9 <strong data-start=\"5280\" data-end=\"5306\">Social Tech europ\u00e9enne<\/strong> donnent rendez-vous au printemps \u00e0 <strong data-start=\"5342\" data-end=\"5354\">Lisbonne<\/strong>, pour le <strong data-start=\"5364\" data-end=\"5418\">deuxi\u00e8me \u00e9v\u00e9nement europ\u00e9en de la Social Good Week<\/strong> !<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; theme_builder_area=&#8221;post_content&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#2B2A5C&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_heading title=&#8221;FAQ \u2014 Social Good Week et \u00e9conomie sociale num\u00e9rique (ESS num\u00e9rique)&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; title_level=&#8221;h2&#8243; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; title_text_color=&#8221;#FFFFFF&#8221;][\/et_pb_heading][et_pb_accordion _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; border_radii=&#8221;on|30px|30px|30px|30px&#8221;][et_pb_accordion_item title=&#8221;Qu\u2019est-ce que la Social Good Week ?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; open=&#8221;on&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p>La <strong data-start=\"5536\" data-end=\"5556\">Social Good Week<\/strong> est un <strong data-start=\"5564\" data-end=\"5648\">mouvement europ\u00e9en d\u00e9di\u00e9 \u00e0 la transformation num\u00e9rique au service du bien commun<\/strong>.<br data-start=\"5649\" data-end=\"5652\" \/>Elle vise \u00e0 <strong data-start=\"5664\" data-end=\"5721\">valoriser les initiatives, les projets et les acteurs<\/strong> qui \u0153uvrent pour un <strong data-start=\"5742\" data-end=\"5786\">num\u00e9rique inclusif, \u00e9thique et solidaire<\/strong>.<\/p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Quelle est la mission du Social Good Accelerator ?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; open=&#8221;off&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p data-start=\"5852\" data-end=\"6116\">Le <strong data-start=\"5855\" data-end=\"5863\">SOGA<\/strong> est un <strong data-start=\"5871\" data-end=\"5899\">think &amp; do tank europ\u00e9en de l&#8217;ESS num\u00e9rique<\/strong>\u00a0fond\u00e9 en 2017.<br data-start=\"5914\" data-end=\"5917\" \/>Sa mission : <strong data-start=\"5930\" data-end=\"6006\">acc\u00e9l\u00e9rer la transformation num\u00e9rique de l\u2019\u00e9conomie sociale et solidaire<\/strong> en Europe, en promouvant la <strong data-start=\"6035\" data-end=\"6087\">coop\u00e9ration, la formation et la recherche-action<\/strong> autour du num\u00e9rique \u00e9thique.<\/p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Pourquoi relancer la Social Good Week en 2022 ?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p>Quatre ans apr\u00e8s sa derni\u00e8re \u00e9dition fran\u00e7aise, le SOGA a souhait\u00e9 <strong data-start=\"6245\" data-end=\"6299\">\u00e9tendre la Social Good Week \u00e0 l\u2019\u00e9chelle europ\u00e9enne<\/strong>.<br data-start=\"6300\" data-end=\"6303\" \/>Objectif : <strong data-start=\"6314\" data-end=\"6365\">rassembler les acteurs du num\u00e9rique responsable<\/strong> et faire de cette rencontre un <strong data-start=\"6397\" data-end=\"6460\">espace de d\u00e9bat, d\u2019exp\u00e9rimentation et de plaidoyer europ\u00e9en<\/strong>.<\/p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Quels sujets ont \u00e9t\u00e9 abord\u00e9s lors de cette premi\u00e8re table ronde ?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p data-start=\"6541\" data-end=\"6572\">Les discussions ont port\u00e9 sur :<\/p>\n<ul data-start=\"6573\" data-end=\"6810\">\n<li data-start=\"6573\" data-end=\"6638\">\n<p data-start=\"6575\" data-end=\"6638\">le <strong data-start=\"6578\" data-end=\"6635\">changement d\u2019\u00e9chelle de l\u2019\u00e9conomie sociale europ\u00e9enne<\/strong>,<\/p>\n<\/li>\n<li data-start=\"6639\" data-end=\"6697\">\n<p data-start=\"6641\" data-end=\"6697\">la <strong data-start=\"6644\" data-end=\"6694\">coop\u00e9ration entre innovation et secteur public<\/strong>,<\/p>\n<\/li>\n<li data-start=\"6698\" data-end=\"6739\">\n<p data-start=\"6700\" data-end=\"6739\">la <strong data-start=\"6703\" data-end=\"6736\">place des femmes dans la tech<\/strong>,<\/p>\n<\/li>\n<li data-start=\"6740\" data-end=\"6810\">\n<p data-start=\"6742\" data-end=\"6810\">et les <strong data-start=\"6749\" data-end=\"6809\">liens entre intelligence artificielle et int\u00e9r\u00eat g\u00e9n\u00e9ral<\/strong>.<\/p>\n<\/li>\n<\/ul>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Quels acteurs \u00e9taient pr\u00e9sents \u00e0 Bruxelles ?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p>Parmi les intervenants :<br data-start=\"6893\" data-end=\"6896\" \/><strong data-start=\"6896\" data-end=\"6915\">Barbara Trachte<\/strong> (R\u00e9gion Bruxelles-Capitale), <strong data-start=\"6945\" data-end=\"6962\">Rowan Barnett<\/strong> (Google Foundation), <strong data-start=\"6984\" data-end=\"6999\">Isidro Laso<\/strong> (Commission europ\u00e9enne), <strong data-start=\"7025\" data-end=\"7041\">Julie Foulon<\/strong> (Girleek), <strong data-start=\"7053\" data-end=\"7070\">Chanel Genova<\/strong> (SocialWare) et <strong data-start=\"7087\" data-end=\"7101\">Carl M\u00f6rch<\/strong> (FARI).<\/p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Quand et o\u00f9 aura lieu le prochain \u00e9v\u00e9nement ?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p data-start=\"7171\" data-end=\"7415\">Le prochain rendez-vous de la <strong data-start=\"7201\" data-end=\"7228\">Social Good Week Europe<\/strong> aura lieu <strong data-start=\"7239\" data-end=\"7271\">au printemps 2023 \u00e0 Lisbonne<\/strong>, autour d\u2019un nouveau cycle de rencontres, d\u2019ateliers et de tables rondes sur la <strong data-start=\"7352\" data-end=\"7415\">coop\u00e9ration europ\u00e9enne en mati\u00e8re de num\u00e9rique responsable.<\/strong><\/p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>Le 25 janvier, le Social Good Accelerator, en partenariat avec Social Economy Europe, a co-organis\u00e9 le premier \u00e9v\u00e9nement de la version europ\u00e9enne de la Social Good Week. Quatre ans apr\u00e8s sa derni\u00e8re \u00e9dition lanc\u00e9e par HelloAsso, le Social Good Accelerator a repris le flambeau en d\u00e9but d'ann\u00e9e pour un premier teaser.<\/p>","protected":false},"author":1,"featured_media":50321,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[192],"tags":[369,116,327],"class_list":["post-50314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-de-soga","tag-evenements","tag-social-good-week","tag-table-ronde"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Social Good Week : retour sur la premi\u00e8re table ronde europ\u00e9enne - SOGA<\/title>\n<meta name=\"description\" content=\"Le Social Good Accelerator et Social Economy Europe ont lanc\u00e9 la premi\u00e8re \u00e9dition europ\u00e9enne de la Social Good Week \u00e0 Bruxelles, autour du changement d\u2019\u00e9chelle de l\u2019\u00e9conomie sociale num\u00e9rique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/socialgoodaccelerator.eu\/fr\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Social Good Week : retour sur la premi\u00e8re table ronde europ\u00e9enne - SOGA\" \/>\n<meta property=\"og:description\" content=\"Le Social Good Accelerator et Social Economy Europe ont lanc\u00e9 la premi\u00e8re \u00e9dition europ\u00e9enne de la Social Good Week \u00e0 Bruxelles, autour du changement d\u2019\u00e9chelle de l\u2019\u00e9conomie sociale num\u00e9rique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/socialgoodaccelerator.eu\/fr\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/\" \/>\n<meta property=\"og:site_name\" content=\"SOGA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SocialGoodAccel.EU\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-28T16:06:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-20T10:31:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/01\/Capture-de%CC%81cran-2022-01-28-a%CC%80-17.24.34.png?fit=1372%2C793&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1372\" \/>\n\t<meta property=\"og:image:height\" content=\"793\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"sogaccelerator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"sogaccelerator\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/2022\\\/01\\\/28\\\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/2022\\\/01\\\/28\\\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\\\/\"},\"author\":{\"name\":\"sogaccelerator\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#\\\/schema\\\/person\\\/0320622db91fd4a2ddef724cbdee0c3e\"},\"headline\":\"Social Good Week : retour sur la premi\u00e8re table ronde europ\u00e9enne\",\"datePublished\":\"2022-01-28T16:06:10+00:00\",\"dateModified\":\"2025-10-20T10:31:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/2022\\\/01\\\/28\\\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\\\/\"},\"wordCount\":2531,\"publisher\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/2022\\\/01\\\/28\\\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/socialgoodaccelerator.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Capture-de%CC%81cran-2022-01-28-a%CC%80-17.24.34.png?fit=1372%2C793&ssl=1\",\"keywords\":[\"\u00c9v\u00e9nements (Connect)\",\"Social Good Week\",\"table ronde\"],\"articleSection\":[\"Actualit\u00e9s de SOGA\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/2022\\\/01\\\/28\\\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\\\/\",\"url\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/2022\\\/01\\\/28\\\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\\\/\",\"name\":\"Social Good Week : retour sur la premi\u00e8re table ronde europ\u00e9enne - SOGA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/2022\\\/01\\\/28\\\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/2022\\\/01\\\/28\\\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/socialgoodaccelerator.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Capture-de%CC%81cran-2022-01-28-a%CC%80-17.24.34.png?fit=1372%2C793&ssl=1\",\"datePublished\":\"2022-01-28T16:06:10+00:00\",\"dateModified\":\"2025-10-20T10:31:42+00:00\",\"description\":\"Le Social Good Accelerator et Social Economy Europe ont lanc\u00e9 la premi\u00e8re \u00e9dition europ\u00e9enne de la Social Good Week \u00e0 Bruxelles, autour du changement d\u2019\u00e9chelle de l\u2019\u00e9conomie sociale num\u00e9rique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/2022\\\/01\\\/28\\\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/socialgoodaccelerator.eu\\\/2022\\\/01\\\/28\\\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/2022\\\/01\\\/28\\\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/socialgoodaccelerator.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Capture-de%CC%81cran-2022-01-28-a%CC%80-17.24.34.png?fit=1372%2C793&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/socialgoodaccelerator.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Capture-de%CC%81cran-2022-01-28-a%CC%80-17.24.34.png?fit=1372%2C793&ssl=1\",\"width\":1372,\"height\":793},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/2022\\\/01\\\/28\\\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Social Good Week : retour sur la premi\u00e8re table ronde europ\u00e9enne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#website\",\"url\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/\",\"name\":\"Social Good Accelerator\",\"description\":\"Acc\u00e9l\u00e9rer l&#039;ESS num\u00e9rique\",\"publisher\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#organization\"},\"alternateName\":\"SOGA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#organization\",\"name\":\"Social Good Accelerator\",\"alternateName\":\"SOGA\",\"url\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/socialgoodaccelerator.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-soga-2026-300x300-1.png?fit=1000%2C1000&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/socialgoodaccelerator.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-soga-2026-300x300-1.png?fit=1000%2C1000&ssl=1\",\"width\":1000,\"height\":1000,\"caption\":\"Social Good Accelerator\"},\"image\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SocialGoodAccel.EU\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@socialgoodaccelerator772\",\"https:\\\/\\\/www.youtube.com\\\/@SocialTechAcademy-eg6hp\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#\\\/schema\\\/person\\\/0320622db91fd4a2ddef724cbdee0c3e\",\"name\":\"sogaccelerator\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99aef05386587650bb056a1275ce2e339bfe398930f37eb7262163da89aad453?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99aef05386587650bb056a1275ce2e339bfe398930f37eb7262163da89aad453?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99aef05386587650bb056a1275ce2e339bfe398930f37eb7262163da89aad453?s=96&d=mm&r=g\",\"caption\":\"sogaccelerator\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Social Good Week : retour sur la premi\u00e8re table ronde europ\u00e9enne - SOGA","description":"Le Social Good Accelerator et Social Economy Europe ont lanc\u00e9 la premi\u00e8re \u00e9dition europ\u00e9enne de la Social Good Week \u00e0 Bruxelles, autour du changement d\u2019\u00e9chelle de l\u2019\u00e9conomie sociale num\u00e9rique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/socialgoodaccelerator.eu\/fr\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/","og_locale":"fr_FR","og_type":"article","og_title":"Social Good Week : retour sur la premi\u00e8re table ronde europ\u00e9enne - SOGA","og_description":"Le Social Good Accelerator et Social Economy Europe ont lanc\u00e9 la premi\u00e8re \u00e9dition europ\u00e9enne de la Social Good Week \u00e0 Bruxelles, autour du changement d\u2019\u00e9chelle de l\u2019\u00e9conomie sociale num\u00e9rique.","og_url":"https:\/\/socialgoodaccelerator.eu\/fr\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/","og_site_name":"SOGA","article_publisher":"https:\/\/www.facebook.com\/SocialGoodAccel.EU\/","article_published_time":"2022-01-28T16:06:10+00:00","article_modified_time":"2025-10-20T10:31:42+00:00","og_image":[{"width":1372,"height":793,"url":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/01\/Capture-de%CC%81cran-2022-01-28-a%CC%80-17.24.34.png?fit=1372%2C793&ssl=1","type":"image\/png"}],"author":"sogaccelerator","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"sogaccelerator","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/socialgoodaccelerator.eu\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/#article","isPartOf":{"@id":"https:\/\/socialgoodaccelerator.eu\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/"},"author":{"name":"sogaccelerator","@id":"https:\/\/socialgoodaccelerator.eu\/#\/schema\/person\/0320622db91fd4a2ddef724cbdee0c3e"},"headline":"Social Good Week : retour sur la premi\u00e8re table ronde europ\u00e9enne","datePublished":"2022-01-28T16:06:10+00:00","dateModified":"2025-10-20T10:31:42+00:00","mainEntityOfPage":{"@id":"https:\/\/socialgoodaccelerator.eu\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/"},"wordCount":2531,"publisher":{"@id":"https:\/\/socialgoodaccelerator.eu\/#organization"},"image":{"@id":"https:\/\/socialgoodaccelerator.eu\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/01\/Capture-de%CC%81cran-2022-01-28-a%CC%80-17.24.34.png?fit=1372%2C793&ssl=1","keywords":["\u00c9v\u00e9nements (Connect)","Social Good Week","table ronde"],"articleSection":["Actualit\u00e9s de SOGA"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/socialgoodaccelerator.eu\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/","url":"https:\/\/socialgoodaccelerator.eu\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/","name":"Social Good Week : retour sur la premi\u00e8re table ronde europ\u00e9enne - SOGA","isPartOf":{"@id":"https:\/\/socialgoodaccelerator.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/socialgoodaccelerator.eu\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/#primaryimage"},"image":{"@id":"https:\/\/socialgoodaccelerator.eu\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/01\/Capture-de%CC%81cran-2022-01-28-a%CC%80-17.24.34.png?fit=1372%2C793&ssl=1","datePublished":"2022-01-28T16:06:10+00:00","dateModified":"2025-10-20T10:31:42+00:00","description":"Le Social Good Accelerator et Social Economy Europe ont lanc\u00e9 la premi\u00e8re \u00e9dition europ\u00e9enne de la Social Good Week \u00e0 Bruxelles, autour du changement d\u2019\u00e9chelle de l\u2019\u00e9conomie sociale num\u00e9rique.","breadcrumb":{"@id":"https:\/\/socialgoodaccelerator.eu\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/socialgoodaccelerator.eu\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/socialgoodaccelerator.eu\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/#primaryimage","url":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/01\/Capture-de%CC%81cran-2022-01-28-a%CC%80-17.24.34.png?fit=1372%2C793&ssl=1","contentUrl":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/01\/Capture-de%CC%81cran-2022-01-28-a%CC%80-17.24.34.png?fit=1372%2C793&ssl=1","width":1372,"height":793},{"@type":"BreadcrumbList","@id":"https:\/\/socialgoodaccelerator.eu\/2022\/01\/28\/social-good-week-retour-sur-la-premiere-table-ronde-europeenne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/socialgoodaccelerator.eu\/"},{"@type":"ListItem","position":2,"name":"Social Good Week : retour sur la premi\u00e8re table ronde europ\u00e9enne"}]},{"@type":"WebSite","@id":"https:\/\/socialgoodaccelerator.eu\/#website","url":"https:\/\/socialgoodaccelerator.eu\/","name":"Social Good Accelerator","description":"Acc\u00e9l\u00e9rer l&#039;ESS num\u00e9rique","publisher":{"@id":"https:\/\/socialgoodaccelerator.eu\/#organization"},"alternateName":"SOGA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/socialgoodaccelerator.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/socialgoodaccelerator.eu\/#organization","name":"Social Good Accelerator","alternateName":"SOGA","url":"https:\/\/socialgoodaccelerator.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/socialgoodaccelerator.eu\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2026\/03\/logo-soga-2026-300x300-1.png?fit=1000%2C1000&ssl=1","contentUrl":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2026\/03\/logo-soga-2026-300x300-1.png?fit=1000%2C1000&ssl=1","width":1000,"height":1000,"caption":"Social Good Accelerator"},"image":{"@id":"https:\/\/socialgoodaccelerator.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SocialGoodAccel.EU\/","https:\/\/www.youtube.com\/@socialgoodaccelerator772","https:\/\/www.youtube.com\/@SocialTechAcademy-eg6hp"]},{"@type":"Person","@id":"https:\/\/socialgoodaccelerator.eu\/#\/schema\/person\/0320622db91fd4a2ddef724cbdee0c3e","name":"sogaccelerator","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/99aef05386587650bb056a1275ce2e339bfe398930f37eb7262163da89aad453?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99aef05386587650bb056a1275ce2e339bfe398930f37eb7262163da89aad453?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99aef05386587650bb056a1275ce2e339bfe398930f37eb7262163da89aad453?s=96&d=mm&r=g","caption":"sogaccelerator"}}]}},"jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":49528,"url":"https:\/\/socialgoodaccelerator.eu\/fr\/2021\/09\/07\/nouveau-conseil-administration-soga-2021\/","url_meta":{"origin":50314,"position":0},"title":"Un nouveau Conseil d\u2019administration pour le SOGA","author":"sogaccelerator","date":"7 septembre 2021","format":false,"excerpt":"Le Social Good Accelerator renouvelle sa gouvernance avec un Conseil d\u2019administration pluraliste, un bureau paritaire et ses premi\u00e8res salari\u00e9es. Une \u00e9tape cl\u00e9 pour l\u2019association europ\u00e9enne.","rel":"","context":"Dans &quot;Actualit\u00e9s de SOGA&quot;","block_context":{"text":"Actualit\u00e9s de SOGA","link":"https:\/\/socialgoodaccelerator.eu\/fr\/category\/actualites-de-soga\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2021\/09\/Capture-de%CC%81cran-2021-09-07-a%CC%80-16.57.03.png?fit=1200%2C673&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2021\/09\/Capture-de%CC%81cran-2021-09-07-a%CC%80-16.57.03.png?fit=1200%2C673&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2021\/09\/Capture-de%CC%81cran-2021-09-07-a%CC%80-16.57.03.png?fit=1200%2C673&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2021\/09\/Capture-de%CC%81cran-2021-09-07-a%CC%80-16.57.03.png?fit=1200%2C673&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2021\/09\/Capture-de%CC%81cran-2021-09-07-a%CC%80-16.57.03.png?fit=1200%2C673&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":51208,"url":"https:\/\/socialgoodaccelerator.eu\/fr\/2022\/07\/20\/social-tech-academy-shu2022-reunion-italie\/","url_meta":{"origin":50314,"position":1},"title":"Retour sur le Social Hackathon Umbria 2022 et la r\u00e9union transnationale de la Social Tech Academy","author":"sogaccelerator","date":"20 juillet 2022","format":false,"excerpt":"D\u00e9but juillet, l'\u00e9quipe de la Social Tech Academy s'est r\u00e9unie pour la premi\u00e8re fois \u00e0 Foligno et Montefalco en Italie pour 4 jours intenses autour de la Social Tech.","rel":"","context":"Dans &quot;Projets europ\u00e9ens&quot;","block_context":{"text":"Projets europ\u00e9ens","link":"https:\/\/socialgoodaccelerator.eu\/fr\/category\/projets-europeens\/"},"img":{"alt_text":"L'\u00e9quipe de Social Tech Academy le 6 juillet \u00e0 Foligno, Italie.","src":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/07\/IMG_1628-scaled.jpg?fit=1200%2C840&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/07\/IMG_1628-scaled.jpg?fit=1200%2C840&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/07\/IMG_1628-scaled.jpg?fit=1200%2C840&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/07\/IMG_1628-scaled.jpg?fit=1200%2C840&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/07\/IMG_1628-scaled.jpg?fit=1200%2C840&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":49802,"url":"https:\/\/socialgoodaccelerator.eu\/fr\/2021\/09\/27\/economie-sociale-ocde-global-action-2021\/","url_meta":{"origin":50314,"position":2},"title":"\u00c9conomie sociale : de la marge au c\u0153ur de l\u2019\u00e9conomie mondiale","author":"sogaccelerator","date":"27 septembre 2021","format":false,"excerpt":"Le Social Good Accelerator a particip\u00e9 \u00e0 la conf\u00e9rence OCDE Global Action, d\u00e9di\u00e9e \u00e0 la promotion internationale de l\u2019\u00e9conomie sociale comme levier de croissance inclusive et durable.","rel":"","context":"Dans &quot;Notes de position&quot;","block_context":{"text":"Notes de position","link":"https:\/\/socialgoodaccelerator.eu\/fr\/category\/notes-de-position\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2021\/09\/oecd_event.jpeg?fit=600%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2021\/09\/oecd_event.jpeg?fit=600%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2021\/09\/oecd_event.jpeg?fit=600%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":47985,"url":"https:\/\/socialgoodaccelerator.eu\/fr\/2021\/04\/02\/numerique-economie-sociale-europe\/","url_meta":{"origin":50314,"position":3},"title":"En pr\u00e9paration de Mannheim : \u00e9change strat\u00e9gique avec Karel Vanderpoorten","author":"sogaccelerator","date":"2 avril 2021","format":false,"excerpt":"\u00c0 l\u2019approche du Sommet europ\u00e9en de l\u2019\u00e9conomie sociale de Mannheim, une\u2026","rel":"","context":"Dans &quot;Projets europ\u00e9ens&quot;","block_context":{"text":"Projets europ\u00e9ens","link":"https:\/\/socialgoodaccelerator.eu\/fr\/category\/projets-europeens\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":55674,"url":"https:\/\/socialgoodaccelerator.eu\/fr\/2020\/09\/28\/lentreprise-va-t-elle-sauver-le-monde\/","url_meta":{"origin":50314,"position":4},"title":"L&#8217;entreprise va t-elle sauver le monde ?","author":"sogaccelerator","date":"28 septembre 2020","format":false,"excerpt":"","rel":"","context":"Dans &quot;SOGA dans la presse&quot;","block_context":{"text":"SOGA dans la presse","link":"https:\/\/socialgoodaccelerator.eu\/fr\/category\/soga-dans-la-presse\/"},"img":{"alt_text":"1200px-Le_Monde.svg","src":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/09\/1200px-Le_Monde.svg_.png?fit=1200%2C276&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/09\/1200px-Le_Monde.svg_.png?fit=1200%2C276&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/09\/1200px-Le_Monde.svg_.png?fit=1200%2C276&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/09\/1200px-Le_Monde.svg_.png?fit=1200%2C276&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/09\/1200px-Le_Monde.svg_.png?fit=1200%2C276&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":50748,"url":"https:\/\/socialgoodaccelerator.eu\/fr\/2022\/05\/13\/sommet-europeen-economie-sociale-strasbourg-soga-2022\/","url_meta":{"origin":50314,"position":5},"title":"Strasbourg : un deuxi\u00e8me sommet europ\u00e9en r\u00e9ussi pour l\u2019\u00e9conomie sociale","author":"sogaccelerator","date":"13 mai 2022","format":false,"excerpt":"Durant ces deux jours, de nombreux ateliers et conf\u00e9rences ont \u00e9t\u00e9 organis\u00e9s, r\u00e9unissant pr\u00e8s de 2000 participants de 14 pays europ\u00e9ens. Ce fut l'occasion de pr\u00e9senter ces id\u00e9es et de rencontrer les acteurs pour coop\u00e9rer sur de futurs projets.","rel":"","context":"Dans &quot;Actualit\u00e9s de SOGA&quot;","block_context":{"text":"Actualit\u00e9s de SOGA","link":"https:\/\/socialgoodaccelerator.eu\/fr\/category\/actualites-de-soga\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/05\/IMG_1022.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/05\/IMG_1022.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/05\/IMG_1022.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/05\/IMG_1022.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/05\/IMG_1022.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/p9J6Qk-d5w","jetpack_featured_media_url":"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2022\/01\/Capture-de%CC%81cran-2022-01-28-a%CC%80-17.24.34.png?fit=1372%2C793&ssl=1","_links":{"self":[{"href":"https:\/\/socialgoodaccelerator.eu\/fr\/wp-json\/wp\/v2\/posts\/50314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socialgoodaccelerator.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/socialgoodaccelerator.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/socialgoodaccelerator.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/socialgoodaccelerator.eu\/fr\/wp-json\/wp\/v2\/comments?post=50314"}],"version-history":[{"count":10,"href":"https:\/\/socialgoodaccelerator.eu\/fr\/wp-json\/wp\/v2\/posts\/50314\/revisions"}],"predecessor-version":[{"id":56052,"href":"https:\/\/socialgoodaccelerator.eu\/fr\/wp-json\/wp\/v2\/posts\/50314\/revisions\/56052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/socialgoodaccelerator.eu\/fr\/wp-json\/wp\/v2\/media\/50321"}],"wp:attachment":[{"href":"https:\/\/socialgoodaccelerator.eu\/fr\/wp-json\/wp\/v2\/media?parent=50314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/socialgoodaccelerator.eu\/fr\/wp-json\/wp\/v2\/categories?post=50314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/socialgoodaccelerator.eu\/fr\/wp-json\/wp\/v2\/tags?post=50314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}