{
    "id": 47171,
    "date": "2018-08-13T15:52:39",
    "date_gmt": "2018-08-13T13:52:39",
    "guid": {
        "rendered": "http:\/\/socialgoodaccelerator.eu\/?p=47171"
    },
    "modified": "2026-03-20T16:07:10",
    "modified_gmt": "2026-03-20T15:07:10",
    "slug": "collaborations-economie-sociale-technologie",
    "status": "publish",
    "type": "post",
    "link": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/",
    "title": {
        "rendered": "#CreatingValueTogether : Notre participation aux conf\u00e9rences \u00e0 Bruxelles"
    },
    "content": {
        "rendered": "[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||on||||||&#8221; text_text_color=&#8221;gcid-body-color&#8221; text_font_size=&#8221;17px&#8221; global_colors_info=&#8221;{%22gcid-body-color%22:%91%22text_text_color%22%93}&#8221;]<p>Le mois dernier, l&#8217;\u00e9quipe du <strong data-start=\"382\" data-end=\"409\">Social Good Accelerator<\/strong> \u00e9tait \u00e0 <strong data-start=\"418\" data-end=\"431\">Bruxelles<\/strong> pour participer aux conf\u00e9rences #CreatingValueTogether organis\u00e9es par la <strong data-start=\"505\" data-end=\"530\">Commission Europ\u00e9enne<\/strong>. L&#8217;occasion pour nous d\u2019assister \u00e0 plusieurs tables rondes et de participer aux <strong data-start=\"611\" data-end=\"624\">workshops<\/strong> sur les types de collaborations entre les acteurs h\u00e9t\u00e9rog\u00e8nes du tissu social europ\u00e9en, et sur les opportunit\u00e9s de collaboration en Europe. Voici notre r\u00e9sum\u00e9 complet !<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Contexte et enjeux des conf\u00e9rences #CreatingValueTogether&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;gcid-body-color&#8221; text_font_size=&#8221;17px&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{%22gcid-body-color%22:%91%22text_text_color%22%93}&#8221; sticky_enabled=&#8221;0&#8243;]<p>Les conf\u00e9rences ont eu lieu \u00e0 Bruxelles les <strong data-start=\"905\" data-end=\"923\">3 et 4 juillet<\/strong> et avaient pour objectif principal la diffusion des premiers r\u00e9sultats de l&#8217;\u00e9tude <strong data-start=\"1006\" data-end=\"1086\">\u201cCooperation between Social Economy Enterprises and Traditional Enterprises\u201d<\/strong> r\u00e9alis\u00e9e par la <a href=\"http:\/\/ec.europa.eu\/growth\/index_fr\" target=\"_blank\" rel=\"noopener\"><strong data-start=\"1103\" data-end=\"1116\">DG Growth<\/strong><\/a> de la <strong data-start=\"1123\" data-end=\"1148\">Commission Europ\u00e9enne<\/strong>. Ces deux journ\u00e9es ont permis de r\u00e9unir un large panel d\u2019acteurs : entrepreneurs, intrapreneurs, social entrepreneurs et autres entit\u00e9s hybrides, pour amorcer le passage de l\u2019analyse th\u00e9orique \u00e0 l\u2019action concr\u00e8te.<\/p>[\/et_pb_text][et_pb_heading title=&#8221;Pourquoi assister \u00e0 cet \u00e9v\u00e9nement ?&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;gcid-body-color&#8221; text_font_size=&#8221;17px&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{%22gcid-body-color%22:%91%22text_text_color%22%93}&#8221; sticky_enabled=&#8221;0&#8243;]<p data-start=\"1409\" data-end=\"1470\">Pour l\u2019\u00e9quipe du SOGA, l\u2019objectif de participer \u00e9tait clair :<\/p>\n<ul data-start=\"1471\" data-end=\"1859\">\n<li data-section-id=\"1ltpwpn\" data-start=\"1471\" data-end=\"1623\">\n<p data-start=\"1473\" data-end=\"1623\"><strong data-start=\"1473\" data-end=\"1513\">Analyser les diff\u00e9rences de maturit\u00e9<\/strong> de l\u2019\u00e9cosyst\u00e8me social europ\u00e9en dans le cadre de notre propre <a href=\"https:\/\/wakelet.com\/wake\/bd3b526e-99a3-45c0-88dc-179615e66e06\" target=\"_blank\" rel=\"noopener\"><strong>\u00e9tude europ\u00e9enne lanc\u00e9e le 19 juin dernier<\/strong><\/a>.<\/p>\n<\/li>\n<li data-section-id=\"nhhc11\" data-start=\"1624\" data-end=\"1765\">\n<p data-start=\"1626\" data-end=\"1765\"><strong data-start=\"1626\" data-end=\"1666\">Comprendre les leviers et challenges<\/strong> rencontr\u00e9s lors des collaborations entre acteurs du secteur social et entreprises traditionnelles.<\/p>\n<\/li>\n<li data-section-id=\"656yx3\" data-start=\"1766\" data-end=\"1859\">\n<p data-start=\"1768\" data-end=\"1859\"><strong data-start=\"1768\" data-end=\"1789\">F\u00e9d\u00e9rer davantage<\/strong> les acteurs <strong data-start=\"1802\" data-end=\"1824\">\u201cSocial Good Tech\u201d<\/strong> au-del\u00e0 des fronti\u00e8res fran\u00e7aises.<\/p>\n<\/li>\n<\/ul>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Les r\u00e9sultats de l\u2019\u00e9tude : Un \u00e9cosyst\u00e8me en croissance mais h\u00e9t\u00e9rog\u00e8ne&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;gcid-body-color&#8221; text_font_size=&#8221;17px&#8221; global_colors_info=&#8221;{%22gcid-body-color%22:%91%22text_text_color%22%93}&#8221;]<p>Une des principales conclusions de cette \u00e9tude a \u00e9t\u00e9 que les <strong data-start=\"2001\" data-end=\"2045\">entreprises de l\u2019\u00e9conomie traditionnelle<\/strong> ne connaissent pas suffisamment l\u2019<strong data-start=\"2080\" data-end=\"2116\">\u00e9conomie circulaire et solidaire<\/strong>, alors que l\u2019inverse est beaucoup plus fr\u00e9quent. Si les collaborations entre ces entit\u00e9s se d\u00e9veloppent de plus en plus, elles restent encore <strong data-start=\"2259\" data-end=\"2279\">tr\u00e8s h\u00e9t\u00e9rog\u00e8nes<\/strong> selon les pays de l&#8217;UE.<\/p>[\/et_pb_text][et_pb_heading title=&#8221;Les trois facteurs cl\u00e9s de r\u00e9ussite&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;gcid-body-color&#8221; text_font_size=&#8221;17px&#8221; global_colors_info=&#8221;{%22gcid-body-color%22:%91%22text_text_color%22%93}&#8221;]<p data-start=\"2350\" data-end=\"2501\">Parmi les \u00e9l\u00e9ments ayant permis de r\u00e9ussir des partenariats entre entreprises sociales et traditionnelles, <strong data-start=\"2457\" data-end=\"2487\">trois facteurs de r\u00e9ussite<\/strong> se d\u00e9gagent :<\/p>\n<ul data-start=\"2502\" data-end=\"2661\">\n<li data-section-id=\"1p8gp8j\" data-start=\"2502\" data-end=\"2548\">\n<p data-start=\"2504\" data-end=\"2548\"><strong data-start=\"2504\" data-end=\"2529\">La confiance mutuelle<\/strong> entre les acteurs.<\/p>\n<\/li>\n<li data-section-id=\"la1t4j\" data-start=\"2549\" data-end=\"2596\">\n<p data-start=\"2551\" data-end=\"2596\"><strong data-start=\"2551\" data-end=\"2579\">L&#8217;alignement strat\u00e9gique<\/strong> des partenaires.<\/p>\n<\/li>\n<li data-section-id=\"y8x9ed\" data-start=\"2597\" data-end=\"2661\">\n<p data-start=\"2599\" data-end=\"2661\"><strong data-start=\"2599\" data-end=\"2626\">Les ressources allou\u00e9es<\/strong> au projet (financi\u00e8res, humaines).<\/p>\n<\/li>\n<\/ul>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;http:\/\/socialgoodaccelerator.eu\/wp-content\/uploads\/2018\/08\/markus-winkler-IrRbSND5EUc-unsplash-scaled.jpg&#8221; title_text=&#8221;croissance&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;163px||0px||false|false&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; column_structure=&#8221;1_3,2_3&#8243;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;http:\/\/socialgoodaccelerator.eu\/wp-content\/uploads\/2018\/08\/paul-skorupskas-7KLa-xLbSXA-unsplash-scaled.jpg&#8221; title_text=&#8221;opportunit\u00e9s&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;92px||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|30px|30px|30px|30px&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Collaborations dans le domaine de la tech : d\u00e9fis et opportunit\u00e9s&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;gcid-body-color&#8221; text_font_size=&#8221;17px&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{%22gcid-body-color%22:%91%22text_text_color%22%93}&#8221; sticky_enabled=&#8221;0&#8243;]<p data-start=\"2737\" data-end=\"2971\">Nous avons aussi particip\u00e9 \u00e0 un <strong data-start=\"2769\" data-end=\"2781\">workshop<\/strong> intitul\u00e9 <strong data-start=\"2791\" data-end=\"2830\">\u201c<a href=\"http:\/\/www.technopolis-group.com\/wp-content\/uploads\/2018\/08\/WS12_NewTechAndDig.pdf\" target=\"_blank\" rel=\"noopener\">Digitalisation &amp; New Technologies<\/a>\u201d<\/strong>, anim\u00e9 par <strong data-start=\"2842\" data-end=\"2859\">Thomas Heimer<\/strong> de Technopolis. Ce workshop a mis en lumi\u00e8re deux principaux d\u00e9fis pour les partenariats <strong data-start=\"2949\" data-end=\"2969\">Social Good Tech<\/strong> :<\/p>\n<ul data-start=\"2972\" data-end=\"3338\">\n<li data-section-id=\"1j7nkl4\" data-start=\"2972\" data-end=\"3224\">\n<p data-start=\"2974\" data-end=\"3224\"><strong data-start=\"2974\" data-end=\"3018\">Diff\u00e9rences de culture organisationnelle<\/strong> : quand une solution digitale est mise en place pour une entreprise, son adaptation dans une organisation \u00e0 but non lucratif peut s\u2019av\u00e9rer difficile \u00e0 cause de cultures organisationnelles tr\u00e8s diff\u00e9rentes.<\/p>\n<\/li>\n<li data-section-id=\"16a7k2d\" data-start=\"3225\" data-end=\"3338\">\n<p data-start=\"3227\" data-end=\"3338\"><strong data-start=\"3227\" data-end=\"3257\">Priorisation des activit\u00e9s<\/strong> : faut-il privil\u00e9gier les activit\u00e9s r\u00e9mun\u00e9r\u00e9es ou les initiatives <strong data-start=\"3324\" data-end=\"3336\">pro bono<\/strong> ?<\/p>\n<\/li>\n<\/ul>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Comment minimiser ces obstacles ?&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;gcid-body-color&#8221; text_font_size=&#8221;17px&#8221; global_colors_info=&#8221;{%22gcid-body-color%22:%91%22text_text_color%22%93}&#8221;]<ul>\n<li data-section-id=\"198e99a\" data-start=\"3382\" data-end=\"3519\">\n<p data-start=\"3384\" data-end=\"3519\">Prendre le temps d&#8217;un <strong data-start=\"3406\" data-end=\"3430\">apprentissage mutuel<\/strong> d\u00e8s le d\u00e9but du partenariat pour comprendre les comp\u00e9tences apport\u00e9es par chaque acteur.<\/p>\n<\/li>\n<li data-section-id=\"kk6bw3\" data-start=\"3520\" data-end=\"3646\">\n<p data-start=\"3522\" data-end=\"3646\">Analyser l\u2019engagement des <strong data-start=\"3548\" data-end=\"3566\">collaborateurs<\/strong> et <strong data-start=\"3570\" data-end=\"3584\">management<\/strong> afin de mieux doser entre les actions r\u00e9mun\u00e9r\u00e9es et pro bono.<\/p>\n<\/li>\n<\/ul>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;http:\/\/socialgoodaccelerator.eu\/wp-content\/uploads\/2020\/11\/note-thanun-GI10ZiPO_3w-unsplash-scaled.jpg&#8221; title_text=&#8221;Monde d&#8217;apr\u00e8s&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-18px||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|30px|30px|30px|30px&#8221; global_colors_info=&#8221;{}&#8221; alt=&#8221;Photo de note thanun sur Unsplash&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Les collaborations : un pont entre l\u2019\u00c9conomie Sociale et la technologie&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;gcid-body-color&#8221; text_font_size=&#8221;17px&#8221; global_colors_info=&#8221;{%22gcid-body-color%22:%91%22text_text_color%22%93}&#8221;]<p>\u00c0 travers cette <strong data-start=\"3744\" data-end=\"3758\">conf\u00e9rence<\/strong>, il est apparu clairement que <strong data-start=\"3789\" data-end=\"3813\">les entit\u00e9s hybrides<\/strong> jouent un r\u00f4le essentiel en tant qu\u2019interm\u00e9diaires entre le <strong data-start=\"3874\" data-end=\"3892\">secteur social<\/strong> et <strong data-start=\"3896\" data-end=\"3907\">la tech<\/strong>. Cr\u00e9er des <strong data-start=\"3919\" data-end=\"3928\">ponts<\/strong> entre ces deux mondes est l\u2019un des objectifs cl\u00e9s du <strong data-start=\"3982\" data-end=\"3990\">SOGA<\/strong>, pour favoriser des <strong data-start=\"4011\" data-end=\"4039\">synergies inter-secteurs<\/strong>.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Qu&#8217;est-ce qu&#8217;on en retient ?&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h2&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][et_pb_heading title=&#8221;Une bonne nouvelle pour l\u2019\u00e9cosyst\u00e8me ESS Fran\u00e7ais&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;gcid-body-color&#8221; text_font_size=&#8221;17px&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{%22gcid-body-color%22:%91%22text_text_color%22%93}&#8221; sticky_enabled=&#8221;0&#8243;]<p>L\u2019\u00e9cosyst\u00e8me de l\u2019<strong data-start=\"4156\" data-end=\"4163\">ESS<\/strong> fran\u00e7ais est l\u2019un des plus d\u00e9velopp\u00e9s d\u2019Europe. Toutefois, un <strong data-start=\"4226\" data-end=\"4253\">manque de collaboration<\/strong> persiste entre les diff\u00e9rents types d&#8217;acteurs, et notamment entre les secteurs <strong data-start=\"4333\" data-end=\"4343\">social<\/strong> et <strong data-start=\"4347\" data-end=\"4355\">tech<\/strong>. En cela, les <strong data-start=\"4370\" data-end=\"4400\">exemples d\u2019Europe de l\u2019Est<\/strong> pourraient offrir des pistes int\u00e9ressantes pour combler ce foss\u00e9. Le <strong data-start=\"4470\" data-end=\"4497\">Social Good Accelerator<\/strong> a donc d\u00e9cid\u00e9 d&#8217;inclure l&#8217;<strong data-start=\"4524\" data-end=\"4535\">Estonie<\/strong> parmi les trois pays \u00e9tudi\u00e9s pour sa <a href=\"http:\/\/socialgoodaccelerator.eu\/en_gb\/nous-soutenir\/\" target=\"_blank\" rel=\"noopener\"><strong>recherche sur le terrain<\/strong><\/a> avec l&#8217;Agence Phare et Pro Bono Lab.<\/p>[\/et_pb_text][et_pb_heading title=&#8221;Une dynamique europ\u00e9enne soutenue&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;gcid-body-color&#8221; text_font_size=&#8221;17px&#8221; global_colors_info=&#8221;{%22gcid-body-color%22:%91%22text_text_color%22%93}&#8221;]<p>Ces conf\u00e9rences marquent un <strong data-start=\"4675\" data-end=\"4697\">\u00e9lan europ\u00e9en fort<\/strong>, soutenu par la Commission europ\u00e9enne, les associations, les partenaires priv\u00e9s engag\u00e9s et la soci\u00e9t\u00e9 civile. <strong data-start=\"4808\" data-end=\"4832\">Les entit\u00e9s hybrides<\/strong>, facilitant la coop\u00e9ration inter-secteurs, sont de plus en plus mises en avant comme des <strong data-start=\"4922\" data-end=\"4933\">moteurs<\/strong> de cette dynamique de collaboration.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>Le mois dernier, l&#8217;\u00e9quipe du Social Good Accelerator \u00e9tait \u00e0 Bruxelles pour participer aux conf\u00e9rences #CreatingValueTogether organis\u00e9es par la Commission Europ\u00e9enne. L&#8217;occasion pour nous d\u2019assister \u00e0 plusieurs tables rondes et [&hellip;]<\/p>",
        "protected": false
    },
    "author": 1,
    "featured_media": 57509,
    "comment_status": "closed",
    "ping_status": "closed",
    "sticky": false,
    "template": "",
    "format": "standard",
    "meta": {
        "_et_pb_use_builder": "on",
        "_et_pb_old_content": "<p>Le mois dernier, l'\u00e9quipe du Social Good Accelerator \u00e9tait \u00e0 Bruxelles pour les conf\u00e9rences<em> <strong>#CreatingValueTogether<\/strong><\/em> organis\u00e9es par la\u00a0Commission Europ\u00e9enne. Nous avons assist\u00e9 \u00e0 diverses tables rondes et particip\u00e9 aux workshops sur les types de <strong>collaborations <\/strong>liants les acteurs h\u00e9t\u00e9rog\u00e8nes du tissu social europ\u00e9en, ainsi que les opportunit\u00e9s de collaborations qui se profilent en Europe\u2026 et <em>on vous dit tout\u00a0!<\/em><\/p><h3><strong><em>Contexte et enjeux<\/em><\/strong><\/h3><p>Organis\u00e9s \u00e0 Bruxelles les 3 et 4 juillet dernier, ces deux jours de conf\u00e9rences avaient pour but la diffusion des premiers r\u00e9sultats de l\u2019\u00e9tude <strong>\u201cCooperation between social economy enterprises and traditional enterprises<\/strong><em><strong>\u201d <\/strong><\/em>de la <a href=\"http:\/\/ec.europa.eu\/growth\/index_en\">DG growth<\/a> <em>(<\/em>Comission Europ\u00e9enne<em>)<\/em>.Il s\u2019agissait ensuite de profiter du large panel d\u2019acteur pr\u00e9sents\u00a0; des entrepreneurs, intrapreneurs, social extra-preneurs et autres entit\u00e9s hybrides, et de l\u2019intelligence collective afin d\u2019amorcer le passage des constats th\u00e9oriques \u00e0 la pratique.<\/p><p>La team SOGA \u00e9tait compos\u00e9e de <em>Jeanne Br\u00e9techer<\/em>, pr\u00e9sidente, <em>Steven Bertal<\/em> secr\u00e9taire et co-fondateur et <span style=\"color: #ff0000;\">moi-m\u00eame, <em>Andr\u00e9a Thillou<\/em>, charg\u00e9e de mission.<\/span> Les int\u00e9r\u00eats de l\u2019association \u00e0 assister aux d\u00e9bats \u00e9taient multiples\u00a0:<\/p><ul><li>Tout d\u2019abord, appr\u00e9hender les diff\u00e9rences de maturit\u00e9 de l\u2019\u00e9cosyst\u00e8me social europ\u00e9en dans le cadre de l\u2019amor\u00e7age de <strong>notre propre \u00e9tude europ\u00e9enne, <a href=\"https:\/\/wakelet.com\/wake\/bd3b526e-99a3-45c0-88dc-179615e66e06\">lanc\u00e9e le 19 juin dernier<\/a>, <\/strong><\/li><li>Comprendre les divers leviers et challenges rencontr\u00e9s lors des collaborations interacteurs et inter-secteurs europ\u00e9ennes,<\/li><li>Et enfin, continuer \u00e0 f\u00e9d\u00e9rer les acteurs \"Social Good Tech\" au-del\u00e0 des fronti\u00e8res fran\u00e7aises.<\/li><\/ul><h3><em><strong>Les r\u00e9sultats\u00a0de l\u2019\u00e9tude\u00a0en bref <\/strong><\/em><\/h3><p><img class=\"wp-image-47190 alignleft\" src=\"http:\/\/socialgoodaccelerator.eu\/wp-content\/uploads\/2018\/08\/Visuel-article-BRU-3.png\" alt=\"\" width=\"377\" height=\"273\" \/>Une des conclusions les plus importantes de l\u2019\u00e9tude fut que les entreprises de l\u2019\u00e9conomie classique ne connaissent pas assez l\u2019\u00e9conomie circulaire\/solidaire. Alors que l\u2019inverse est faux ! Ainsi, m\u00eame si les collaborations entre les entit\u00e9s se d\u00e9veloppent de plus en plus, ces d\u00e9veloppements restent tr\u00e8s h\u00e9t\u00e9rog\u00e8nes selon les pays de l\u2019UE. Le challenge principal\u00a0rencontr\u00e9 lors de la construction de partenariat\u00a0n\u2019est autre que <strong>l\u2019asym\u00e9trie de pouvoirs <\/strong>entre ses parties prenantes.<\/p><p>Apr\u00e8s avoir abord\u00e9 les principaux leviers et challenges des partenariats entreprises sociales et traditionnels constat\u00e9s lors de l\u2019\u00e9tude, on en a conclu que les 3 facteurs de r\u00e9ussite les plus influents sont\u00a0: la confiance que s\u2019accordent les diff\u00e9rents acteurs, l\u2019alignement entre le partenariat et la strat\u00e9gie des deux (voire plus) entit\u00e9s ainsi que les ressources allou\u00e9es au projet (financi\u00e8res, humaines,\u2026).<\/p><p><strong><em>Quid des collaborations sp\u00e9cifiques au domaine de la tech\u00a0?<\/em><\/strong><\/p><p>Enfin, nous avons enfin assist\u00e9 au workshop <a href=\"http:\/\/www.technopolis-group.com\/wp-content\/uploads\/2018\/08\/WS12_NewTechAndDig.pdf\">\u00ab\u00a0Digitalisation & New technologies\u00a0\u00bb,<\/a> anim\u00e9 par Thomas Heimer (Technopolis) charg\u00e9 de l\u2019\u00e9tude. Il semble avoir identifi\u00e9 deux principaux challenges pour des partenariats relatifs \u00e0\/utilisant la tech\u00a0:<\/p><ul><li><strong>La diff\u00e9rence de culture <\/strong>: le r\u00e9sultat peut \u00eatre chaotique quand l\u2019Europe impl\u00e9mente une solution sur mesure pour une entreprise, \u00e0 l'aide une association par exemple dont la culture organisationnelle est bien diff\u00e9rente d'une grosse structure.<br \/><em>Comment le minimiser\u00a0? <\/em>Prendre le temps d\u2019un apprentissage mutuel \u00e0 chaque d\u00e9but de partenariat et se concentrer sur les comp\u00e9tences qu\u2019on pourrait s'apporter mutuellement plut\u00f4t que de se focaliser sur les diff\u00e9rences.<\/li><li><strong>Les difficult\u00e9s \u00e0 prioriser<\/strong> : faut-il mettre l'accent sur l\u2019activit\u00e9 client (r\u00e9mun\u00e9r\u00e9e) ou Pro Bono\u00a0(gratuite)?<br \/><em>Comment g\u00e9rer? <\/em>Il faut analyser et utiliser l\u2019engagement du management et des collaborateurs afin de doser entre les deux activit\u00e9s.<\/li><\/ul><p><em>Retrouvez les r\u00e9sum\u00e9s des conf\u00e9rences de restitution de l\u2019\u00e9tude et du workshop, sous forme d\u2019illustration \u00e0 la fin de cet article. <\/em><\/p><h3><em><strong>Qu\u2019est-ce qu\u2019on en retient\u00a0? \u00a0<\/strong><\/em><\/h3><p>Bonne nouvelle\u00a0! L\u2019\u00e9cosyst\u00e8me ESS fran\u00e7ais est l\u2019un <strong>des \u00e9cosyst\u00e8mes sociaux les plus d\u00e9velopp\u00e9s d\u2019Europe. <\/strong>Cependant, nous manquons encore cruellement de collaboration entre les diff\u00e9rents types d'acteur et surtout entre les diff\u00e9rents secteurs... Social et Tech par exemple\u00a0! Dans ces domaines, nous gagnerions beaucoup \u00e0 apprendre des exemples d\u2019Europe de l\u2019Est. C\u2019est aussi pourquoi nous avons d\u00e9cid\u00e9 d\u2019inclure l\u2019Estonie en tant qu\u2019un des trois pays \u00e9tudi\u00e9s par Pro Bono Lab et l\u2019Agence Phare pour <a href=\"http:\/\/socialgoodaccelerator.eu\/en_gb\/nous-soutenir\/\">l\u2019\u00e9tude Europ\u00e9enne du Social Good Accelerator<\/a>.<\/p><p>\u00a0<\/p><p>Ces conf\u00e9rences marquent\u00a0donc le lancement d\u2019un <strong>vrai \u00e9lan europ\u00e9en<\/strong> soutenu pour la Commission mais aussi par les associations, des partenaires priv\u00e9s investis et la soci\u00e9t\u00e9 civile pour plus de collaborations. Les entit\u00e9s hybrides sont de plus en plus mises en avant en tant qu\u2019<strong>interm\u00e9diaire clef permettant de cr\u00e9er des <\/strong><strong>synergies inter-secteurs. <\/strong>Cr\u00e9er des ponts entre les acteurs\u00a0c\u2019est ce pourquoi les membres du SOGA se mobilisent !<\/p><p>\u00a0<\/p><p><img class=\"alignnone size-full wp-image-47173\" src=\"http:\/\/socialgoodaccelerator.eu\/wp-content\/uploads\/2018\/08\/Pic-2.jpg\" alt=\"\" width=\"1460\" height=\"1703\" \/><\/p><p>\u00a0<\/p><p><img class=\"alignnone size-full wp-image-47172\" src=\"http:\/\/socialgoodaccelerator.eu\/wp-content\/uploads\/2018\/08\/Pic-1.jpg\" alt=\"\" width=\"1454\" height=\"1696\" \/><\/p>",
        "_et_gb_content_width": "",
        "_jetpack_newsletter_access": "",
        "_jetpack_dont_email_post_to_subs": true,
        "_jetpack_newsletter_tier_id": 0,
        "_jetpack_memberships_contains_paywalled_content": false,
        "_jetpack_memberships_contains_paid_content": false,
        "footnotes": ""
    },
    "categories": [
        192
    ],
    "tags": [],
    "class_list": [
        "post-47171",
        "post",
        "type-post",
        "status-publish",
        "format-standard",
        "has-post-thumbnail",
        "hentry",
        "category-actualites-de-soga"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Collaborations entre \u00c9conomie Sociale et technologie : enjeux et perspectives<\/title>\n<meta name=\"description\" content=\"Collaborations entre \u00c9conomie Sociale et technologie : enjeux et perspectives\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collaborations entre \u00c9conomie Sociale et technologie : enjeux et perspectives\" \/>\n<meta property=\"og:description\" content=\"Collaborations entre \u00c9conomie Sociale et technologie : enjeux et perspectives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/\" \/>\n<meta property=\"og:site_name\" content=\"SOGA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SocialGoodAccel.EU\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-13T13:52:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T15:07:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2018\/08\/paul-skorupskas-7KLa-xLbSXA-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sogaccelerator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sogaccelerator\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/en_gb\\\/2018\\\/08\\\/13\\\/collaborations-economie-sociale-technologie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/en_gb\\\/2018\\\/08\\\/13\\\/collaborations-economie-sociale-technologie\\\/\"},\"author\":{\"name\":\"sogaccelerator\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#\\\/schema\\\/person\\\/0320622db91fd4a2ddef724cbdee0c3e\"},\"headline\":\"#CreatingValueTogether : Notre participation aux conf\u00e9rences \u00e0 Bruxelles\",\"datePublished\":\"2018-08-13T13:52:39+00:00\",\"dateModified\":\"2026-03-20T15:07:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/en_gb\\\/2018\\\/08\\\/13\\\/collaborations-economie-sociale-technologie\\\/\"},\"wordCount\":1688,\"publisher\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/en_gb\\\/2018\\\/08\\\/13\\\/collaborations-economie-sociale-technologie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/socialgoodaccelerator.eu\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/paul-skorupskas-7KLa-xLbSXA-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1\",\"articleSection\":[\"Actualit\u00e9s de SOGA\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/en_gb\\\/2018\\\/08\\\/13\\\/collaborations-economie-sociale-technologie\\\/\",\"url\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/en_gb\\\/2018\\\/08\\\/13\\\/collaborations-economie-sociale-technologie\\\/\",\"name\":\"Collaborations entre \u00c9conomie Sociale et technologie : enjeux et perspectives\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/en_gb\\\/2018\\\/08\\\/13\\\/collaborations-economie-sociale-technologie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/en_gb\\\/2018\\\/08\\\/13\\\/collaborations-economie-sociale-technologie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/socialgoodaccelerator.eu\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/paul-skorupskas-7KLa-xLbSXA-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1\",\"datePublished\":\"2018-08-13T13:52:39+00:00\",\"dateModified\":\"2026-03-20T15:07:10+00:00\",\"description\":\"Collaborations entre \u00c9conomie Sociale et technologie : enjeux et perspectives\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/en_gb\\\/2018\\\/08\\\/13\\\/collaborations-economie-sociale-technologie\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/socialgoodaccelerator.eu\\\/en_gb\\\/2018\\\/08\\\/13\\\/collaborations-economie-sociale-technologie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/en_gb\\\/2018\\\/08\\\/13\\\/collaborations-economie-sociale-technologie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/socialgoodaccelerator.eu\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/paul-skorupskas-7KLa-xLbSXA-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/socialgoodaccelerator.eu\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/paul-skorupskas-7KLa-xLbSXA-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1\",\"width\":2560,\"height\":1707,\"caption\":\"paul-skorupskas-7KLa-xLbSXA-unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/en_gb\\\/2018\\\/08\\\/13\\\/collaborations-economie-sociale-technologie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#CreatingValueTogether : Notre participation aux conf\u00e9rences \u00e0 Bruxelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#website\",\"url\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/\",\"name\":\"Social Good Accelerator\",\"description\":\"Acc\u00e9l\u00e9rer l&#039;ESS num\u00e9rique\",\"publisher\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#organization\"},\"alternateName\":\"SOGA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#organization\",\"name\":\"Social Good Accelerator\",\"alternateName\":\"SOGA\",\"url\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/socialgoodaccelerator.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-soga-2026-300x300-1.png?fit=1000%2C1000&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/socialgoodaccelerator.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-soga-2026-300x300-1.png?fit=1000%2C1000&ssl=1\",\"width\":1000,\"height\":1000,\"caption\":\"Social Good Accelerator\"},\"image\":{\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SocialGoodAccel.EU\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@socialgoodaccelerator772\",\"https:\\\/\\\/www.youtube.com\\\/@SocialTechAcademy-eg6hp\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/socialgoodaccelerator.eu\\\/#\\\/schema\\\/person\\\/0320622db91fd4a2ddef724cbdee0c3e\",\"name\":\"sogaccelerator\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99aef05386587650bb056a1275ce2e339bfe398930f37eb7262163da89aad453?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99aef05386587650bb056a1275ce2e339bfe398930f37eb7262163da89aad453?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99aef05386587650bb056a1275ce2e339bfe398930f37eb7262163da89aad453?s=96&d=mm&r=g\",\"caption\":\"sogaccelerator\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "Collaborations entre \u00c9conomie Sociale et technologie : enjeux et perspectives",
        "description": "Collaborations entre \u00c9conomie Sociale et technologie : enjeux et perspectives",
        "robots": {
            "index": "index",
            "follow": "follow",
            "max-snippet": "max-snippet:-1",
            "max-image-preview": "max-image-preview:large",
            "max-video-preview": "max-video-preview:-1"
        },
        "canonical": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/",
        "og_locale": "en_GB",
        "og_type": "article",
        "og_title": "Collaborations entre \u00c9conomie Sociale et technologie : enjeux et perspectives",
        "og_description": "Collaborations entre \u00c9conomie Sociale et technologie : enjeux et perspectives",
        "og_url": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/",
        "og_site_name": "SOGA",
        "article_publisher": "https:\/\/www.facebook.com\/SocialGoodAccel.EU\/",
        "article_published_time": "2018-08-13T13:52:39+00:00",
        "article_modified_time": "2026-03-20T15:07:10+00:00",
        "og_image": [
            {
                "width": 2560,
                "height": 1707,
                "url": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2018\/08\/paul-skorupskas-7KLa-xLbSXA-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1",
                "type": "image\/jpeg"
            }
        ],
        "author": "sogaccelerator",
        "twitter_card": "summary_large_image",
        "twitter_misc": {
            "Written by": "sogaccelerator",
            "Estimated reading time": "4 minutes"
        },
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "Article",
                    "@id": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/#article",
                    "isPartOf": {
                        "@id": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/"
                    },
                    "author": {
                        "name": "sogaccelerator",
                        "@id": "https:\/\/socialgoodaccelerator.eu\/#\/schema\/person\/0320622db91fd4a2ddef724cbdee0c3e"
                    },
                    "headline": "#CreatingValueTogether : Notre participation aux conf\u00e9rences \u00e0 Bruxelles",
                    "datePublished": "2018-08-13T13:52:39+00:00",
                    "dateModified": "2026-03-20T15:07:10+00:00",
                    "mainEntityOfPage": {
                        "@id": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/"
                    },
                    "wordCount": 1688,
                    "publisher": {
                        "@id": "https:\/\/socialgoodaccelerator.eu\/#organization"
                    },
                    "image": {
                        "@id": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/#primaryimage"
                    },
                    "thumbnailUrl": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2018\/08\/paul-skorupskas-7KLa-xLbSXA-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1",
                    "articleSection": [
                        "Actualit\u00e9s de SOGA"
                    ],
                    "inLanguage": "en-GB"
                },
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/",
                    "url": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/",
                    "name": "Collaborations entre \u00c9conomie Sociale et technologie : enjeux et perspectives",
                    "isPartOf": {
                        "@id": "https:\/\/socialgoodaccelerator.eu\/#website"
                    },
                    "primaryImageOfPage": {
                        "@id": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/#primaryimage"
                    },
                    "image": {
                        "@id": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/#primaryimage"
                    },
                    "thumbnailUrl": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2018\/08\/paul-skorupskas-7KLa-xLbSXA-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1",
                    "datePublished": "2018-08-13T13:52:39+00:00",
                    "dateModified": "2026-03-20T15:07:10+00:00",
                    "description": "Collaborations entre \u00c9conomie Sociale et technologie : enjeux et perspectives",
                    "breadcrumb": {
                        "@id": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/#breadcrumb"
                    },
                    "inLanguage": "en-GB",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "ImageObject",
                    "inLanguage": "en-GB",
                    "@id": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/#primaryimage",
                    "url": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2018\/08\/paul-skorupskas-7KLa-xLbSXA-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1",
                    "contentUrl": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2018\/08\/paul-skorupskas-7KLa-xLbSXA-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1",
                    "width": 2560,
                    "height": 1707,
                    "caption": "paul-skorupskas-7KLa-xLbSXA-unsplash"
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2018\/08\/13\/collaborations-economie-sociale-technologie\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "Accueil",
                            "item": "https:\/\/socialgoodaccelerator.eu\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "#CreatingValueTogether : Notre participation aux conf\u00e9rences \u00e0 Bruxelles"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/socialgoodaccelerator.eu\/#website",
                    "url": "https:\/\/socialgoodaccelerator.eu\/",
                    "name": "Social Good Accelerator",
                    "description": "Acc\u00e9l\u00e9rer l&#039;ESS num\u00e9rique",
                    "publisher": {
                        "@id": "https:\/\/socialgoodaccelerator.eu\/#organization"
                    },
                    "alternateName": "SOGA",
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/socialgoodaccelerator.eu\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-GB"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/socialgoodaccelerator.eu\/#organization",
                    "name": "Social Good Accelerator",
                    "alternateName": "SOGA",
                    "url": "https:\/\/socialgoodaccelerator.eu\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "en-GB",
                        "@id": "https:\/\/socialgoodaccelerator.eu\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2026\/03\/logo-soga-2026-300x300-1.png?fit=1000%2C1000&ssl=1",
                        "contentUrl": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2026\/03\/logo-soga-2026-300x300-1.png?fit=1000%2C1000&ssl=1",
                        "width": 1000,
                        "height": 1000,
                        "caption": "Social Good Accelerator"
                    },
                    "image": {
                        "@id": "https:\/\/socialgoodaccelerator.eu\/#\/schema\/logo\/image\/"
                    },
                    "sameAs": [
                        "https:\/\/www.facebook.com\/SocialGoodAccel.EU\/",
                        "https:\/\/www.youtube.com\/@socialgoodaccelerator772",
                        "https:\/\/www.youtube.com\/@SocialTechAcademy-eg6hp"
                    ]
                },
                {
                    "@type": "Person",
                    "@id": "https:\/\/socialgoodaccelerator.eu\/#\/schema\/person\/0320622db91fd4a2ddef724cbdee0c3e",
                    "name": "sogaccelerator",
                    "image": {
                        "@type": "ImageObject",
                        "inLanguage": "en-GB",
                        "@id": "https:\/\/secure.gravatar.com\/avatar\/99aef05386587650bb056a1275ce2e339bfe398930f37eb7262163da89aad453?s=96&d=mm&r=g",
                        "url": "https:\/\/secure.gravatar.com\/avatar\/99aef05386587650bb056a1275ce2e339bfe398930f37eb7262163da89aad453?s=96&d=mm&r=g",
                        "contentUrl": "https:\/\/secure.gravatar.com\/avatar\/99aef05386587650bb056a1275ce2e339bfe398930f37eb7262163da89aad453?s=96&d=mm&r=g",
                        "caption": "sogaccelerator"
                    }
                }
            ]
        }
    },
    "jetpack_likes_enabled": true,
    "jetpack-related-posts": [
        {
            "id": 47857,
            "url": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2020\/11\/09\/interview-axelle-lemaire-soga\/",
            "url_meta": {
                "origin": 47171,
                "position": 0
            },
            "title": "Interview de la marraine du SOGA : Axelle Lemaire",
            "author": "sogaccelerator",
            "date": "9 November 2020",
            "format": false,
            "excerpt": "As a great honor for the team and our European community, Axelle Lemaire has agreed to become the Sponsor of the Social Good Accelerator EU in september 2020. Former French Secretary of State for Digital, at the origin of the law for a committed digital Republic, ...",
            "rel": "",
            "context": "In &quot;Actualit\u00e9s de SOGA&quot;",
            "block_context": {
                "text": "Actualit\u00e9s de SOGA",
                "link": "https:\/\/socialgoodaccelerator.eu\/en_gb\/category\/actualites-de-soga\/"
            },
            "img": {
                "alt_text": "",
                "src": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2020\/11\/Axelle-Lemaire.png?fit=765%2C765&ssl=1&resize=350%2C200",
                "width": 350,
                "height": 200,
                "srcset": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2020\/11\/Axelle-Lemaire.png?fit=765%2C765&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2020\/11\/Axelle-Lemaire.png?fit=765%2C765&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2020\/11\/Axelle-Lemaire.png?fit=765%2C765&ssl=1&resize=700%2C400 2x"
            },
            "classes": []
        },
        {
            "id": 50996,
            "url": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2022\/06\/02\/transition-pathways-economie-proximite-social-tech\/",
            "url_meta": {
                "origin": 47171,
                "position": 1
            },
            "title": "Transition Pathways : des solutions pour l\u2019\u00e9conomie de proximit\u00e9 et la Social Tech",
            "author": "sogaccelerator",
            "date": "2 June 2022",
            "format": false,
            "excerpt": "Dans le cadre de la consultation europ\u00e9enne sur les Transition Pathways for Social Economy, le Social Good Accelerator a publi\u00e9 une note de contribution visant \u00e0 proposer des solutions concr\u00e8tes pour renforcer l\u2019\u00e9conomie sociale dans les transitions num\u00e9rique et \u00e9cologique. Cette contribution met en avant deux leviers principaux : l\u2019\u00e9conomie\u2026",
            "rel": "",
            "context": "In &quot;Notes de position&quot;",
            "block_context": {
                "text": "Notes de position",
                "link": "https:\/\/socialgoodaccelerator.eu\/en_gb\/category\/notes-de-position\/"
            },
            "img": {
                "alt_text": "",
                "src": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2021\/05\/euses-OECD-2.png?fit=1038%2C666&ssl=1&resize=350%2C200",
                "width": 350,
                "height": 200,
                "srcset": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2021\/05\/euses-OECD-2.png?fit=1038%2C666&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2021\/05\/euses-OECD-2.png?fit=1038%2C666&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2021\/05\/euses-OECD-2.png?fit=1038%2C666&ssl=1&resize=700%2C400 2x"
            },
            "classes": []
        },
        {
            "id": 56003,
            "url": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2025\/10\/21\/nec-ess-2025-intelligence-artificielle-ou-cooperative\/",
            "url_meta": {
                "origin": 47171,
                "position": 2
            },
            "title": "NEC ESS 2025 : Intelligence artificielle ou coop\u00e9rative ?",
            "author": "sogaccelerator",
            "date": "21 October 2025",
            "format": false,
            "excerpt": "Du 25 au 27 novembre 2025, le Social Good Accelerator (SOGA) et ses partenaires invitent les acteurs europ\u00e9ens du num\u00e9rique \u00e9thique et de l\u2019\u00e9conomie sociale et solidaire \u00e0 une nouvelle \u00e9dition de Num\u00e9rique en Commun[s] ESS Europe (NEC ESS).",
            "rel": "",
            "context": "In &quot;Actualit\u00e9s de SOGA&quot;",
            "block_context": {
                "text": "Actualit\u00e9s de SOGA",
                "link": "https:\/\/socialgoodaccelerator.eu\/en_gb\/category\/actualites-de-soga\/"
            },
            "img": {
                "alt_text": "NEC ESS 2025",
                "src": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2025\/10\/NEC-ESS-PROGRAMME-1.png?fit=1200%2C800&ssl=1&resize=350%2C200",
                "width": 350,
                "height": 200,
                "srcset": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2025\/10\/NEC-ESS-PROGRAMME-1.png?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2025\/10\/NEC-ESS-PROGRAMME-1.png?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2025\/10\/NEC-ESS-PROGRAMME-1.png?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2025\/10\/NEC-ESS-PROGRAMME-1.png?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"
            },
            "classes": []
        },
        {
            "id": 47681,
            "url": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2020\/05\/13\/entretien-denis-stokkink-role-du-geces\/",
            "url_meta": {
                "origin": 47171,
                "position": 3
            },
            "title": "Entretien avec Denis Stokkink : le r\u00f4le du GECES",
            "author": "sogaccelerator",
            "date": "13 May 2020",
            "format": false,
            "excerpt": "",
            "rel": "",
            "context": "In &quot;Notes de position&quot;",
            "block_context": {
                "text": "Notes de position",
                "link": "https:\/\/socialgoodaccelerator.eu\/en_gb\/category\/notes-de-position\/"
            },
            "img": {
                "alt_text": "Denis Stokkink",
                "src": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2020\/05\/OIP.d6kjMp-AC5QvTWU5vGd2AgHaHa.webp?fit=474%2C474&ssl=1&resize=350%2C200",
                "width": 350,
                "height": 200
            },
            "classes": []
        },
        {
            "id": 52851,
            "url": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2023\/02\/22\/rejoignez-notre-formation-de-formateurs-a-leconomie-sociale-numerique\/",
            "url_meta": {
                "origin": 47171,
                "position": 4
            },
            "title": "Rejoignez notre formation de formateurs \u00e0 l\u2019\u00e9conomie sociale num\u00e9rique",
            "author": "sogaccelerator",
            "date": "22 February 2023",
            "format": false,
            "excerpt": "Vous \u00eates formateur ou formatrice dans l\u2019\u00e9conomie sociale et solidaire ? Dans le cadre du projet europ\u00e9en Social Tech Academy, nous vous proposons une formation gratuite d\u2019une journ\u00e9e en ligne d\u00e9di\u00e9e aux comp\u00e9tences num\u00e9riques dans l\u2019\u00e9conomie sociale.",
            "rel": "",
            "context": "In &quot;Actualit\u00e9s de SOGA&quot;",
            "block_context": {
                "text": "Actualit\u00e9s de SOGA",
                "link": "https:\/\/socialgoodaccelerator.eu\/en_gb\/category\/actualites-de-soga\/"
            },
            "img": {
                "alt_text": "",
                "src": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2023\/02\/Invitation-en-anglais-format-carenews-langue-avec-maj-OK.png?fit=750%2C500&ssl=1&resize=350%2C200",
                "width": 350,
                "height": 200,
                "srcset": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2023\/02\/Invitation-en-anglais-format-carenews-langue-avec-maj-OK.png?fit=750%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2023\/02\/Invitation-en-anglais-format-carenews-langue-avec-maj-OK.png?fit=750%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2023\/02\/Invitation-en-anglais-format-carenews-langue-avec-maj-OK.png?fit=750%2C500&ssl=1&resize=700%2C400 2x"
            },
            "classes": []
        },
        {
            "id": 55275,
            "url": "https:\/\/socialgoodaccelerator.eu\/en_gb\/2022\/02\/20\/lettre-ouverte-ancrer-less-dans-son-avenir-numerique\/",
            "url_meta": {
                "origin": 47171,
                "position": 5
            },
            "title": "Lettre ouverte &#8211; Ancrer l\u2019ESS dans son avenir num\u00e9rique",
            "author": "sogaccelerator",
            "date": "20 February 2022",
            "format": false,
            "excerpt": "",
            "rel": "",
            "context": "In &quot;Notes de position&quot;",
            "block_context": {
                "text": "Notes de position",
                "link": "https:\/\/socialgoodaccelerator.eu\/en_gb\/category\/notes-de-position\/"
            },
            "img": {
                "alt_text": "",
                "src": "",
                "width": 0,
                "height": 0
            },
            "classes": []
        }
    ],
    "jetpack_sharing_enabled": true,
    "jetpack_shortlink": "https:\/\/wp.me\/p9J6Qk-cgP",
    "jetpack_featured_media_url": "https:\/\/i0.wp.com\/socialgoodaccelerator.eu\/wp-content\/uploads\/2018\/08\/paul-skorupskas-7KLa-xLbSXA-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1",
    "_links": {
        "self": [
            {
                "href": "https:\/\/socialgoodaccelerator.eu\/en_gb\/wp-json\/wp\/v2\/posts\/47171",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/socialgoodaccelerator.eu\/en_gb\/wp-json\/wp\/v2\/posts"
            }
        ],
        "about": [
            {
                "href": "https:\/\/socialgoodaccelerator.eu\/en_gb\/wp-json\/wp\/v2\/types\/post"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/socialgoodaccelerator.eu\/en_gb\/wp-json\/wp\/v2\/users\/1"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/socialgoodaccelerator.eu\/en_gb\/wp-json\/wp\/v2\/comments?post=47171"
            }
        ],
        "version-history": [
            {
                "count": 7,
                "href": "https:\/\/socialgoodaccelerator.eu\/en_gb\/wp-json\/wp\/v2\/posts\/47171\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 57510,
                "href": "https:\/\/socialgoodaccelerator.eu\/en_gb\/wp-json\/wp\/v2\/posts\/47171\/revisions\/57510"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/socialgoodaccelerator.eu\/en_gb\/wp-json\/wp\/v2\/media\/57509"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/socialgoodaccelerator.eu\/en_gb\/wp-json\/wp\/v2\/media?parent=47171"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "category",
                "embeddable": true,
                "href": "https:\/\/socialgoodaccelerator.eu\/en_gb\/wp-json\/wp\/v2\/categories?post=47171"
            },
            {
                "taxonomy": "post_tag",
                "embeddable": true,
                "href": "https:\/\/socialgoodaccelerator.eu\/en_gb\/wp-json\/wp\/v2\/tags?post=47171"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}